{"id":198,"date":"2013-09-24T09:53:12","date_gmt":"2013-09-24T07:53:12","guid":{"rendered":"https:\/\/artif.com\/blog\/?p=198"},"modified":"2022-01-31T10:35:15","modified_gmt":"2022-01-31T09:35:15","slug":"neue-typo3-website-fuer-das-projekt-selbststaendige-schule","status":"publish","type":"post","link":"https:\/\/artif.com\/blog\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html","title":{"rendered":"Neue TYPO3-Website f\u00fcr das Projekt &#8222;Selbstst\u00e4ndige Schule&#8220;"},"content":{"rendered":"<p>Die Inhalte und das Design wurde geliefert. Die Umsetzung in standardkonformes HTML und CSS und die Integration in das TYPO3-CMS erfolgte durch artif. Da die die n\u00e4chste LTS-Version 6.2 des TYPO3-CMS vor der T\u00fcr steht wurde die Website mit der aktuellen Version 6.1.5 entwickelt. Ein Upgrade von der Version 6.1 auf die Version 6.2 LTS, die noch dieses Jahr in der finalen Version ver\u00f6ffentlicht werden soll, wird dann sp\u00e4ter durchgef\u00fchrt.<!--more--><\/p>\n<p>Das Projekt Selbstst\u00e4ndige Schule ist ein gemeinsam initiiertes Projekt der SCHULEWIRTSCHAFT Baden-W\u00fcrttemberg, der Arbeitgeberverb\u00e4nde Baden-W\u00fcrttemberg und der MTO Psychologische Forschung und Beratung GmbH in enger Kooperation mit dem Ministerium f\u00fcr Kultus, Jugend und Sport Baden-W\u00fcrttemberg.<\/p>\n<figure id=\"attachment_199\" aria-describedby=\"caption-attachment-199\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/artif.com\/blog\/wp-content\/uploads\/2013\/09\/Selbst\u00e4ndige-Schule-www_selbstst\u00e4ndige-schule_de.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-199 \" title=\"Projekt Selbst\u00e4ndige Schule www.selbstst\u00e4ndige-schule.de\" src=\"https:\/\/artif.com\/blog\/wp-content\/uploads\/2013\/09\/Selbst\u00e4ndige-Schule-www_selbstst\u00e4ndige-schule_de-300x229.png\" alt=\"Screenshot Startseite Projekt Selbst\u00e4ndige Schule\" width=\"300\" height=\"229\" \/><\/a><figcaption id=\"caption-attachment-199\" class=\"wp-caption-text\">Screenshot Startseite Projekt Selbst\u00e4ndige Schule www.selbstst\u00e4ndige-schule.de<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Die Inhalte und das Design wurde geliefert. Die Umsetzung in standardkonformes HTML und CSS und die Integration in das TYPO3-CMS erfolgte durch artif. Da die die n\u00e4chste LTS-Version 6.2 des TYPO3-CMS vor der T\u00fcr steht wurde die Website mit der aktuellen Version 6.1.5 entwickelt. Ein Upgrade von der Version 6.1 auf die Version 6.2 LTS,&#8230;<\/p>\n<p><span class=\"hidden-desktop article_mobileCategory\"><a href=\"https:\/\/artif.com\/blog\/category\/projekte\" title=\"Alle Artikel in Projekte\"><span class=\"hidden-desktop articleCategory_icon icon-projekte\"><\/span> Projekte<\/a><\/span><a class=\"article_moreLink\" href=\"https:\/\/artif.com\/blog\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html\" aria-label=\"Weiterlesen: Neue TYPO3-Website f\u00fcr das Projekt &#8222;Selbstst\u00e4ndige Schule&#8220;\"><span class=\"icon icon-readmore\"><\/span> Weiterlesen<\/a><\/p>\n","protected":false},"author":4,"featured_media":199,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[34,33],"class_list":["post-198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-projekte","tag-projekte","tag-typo3"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neue TYPO3-Website f\u00fcr das Projekt &quot;Selbstst\u00e4ndige Schule&quot; - Blog artif T\u00fcbingen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/artif.com\/blog\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neue TYPO3-Website f\u00fcr das Projekt &quot;Selbstst\u00e4ndige Schule&quot; - Blog artif T\u00fcbingen\" \/>\n<meta property=\"og:description\" content=\"Die Inhalte und das Design wurde geliefert. Die Umsetzung in standardkonformes HTML und CSS und die Integration in das TYPO3-CMS erfolgte durch artif. Da die die n\u00e4chste LTS-Version 6.2 des TYPO3-CMS vor der T\u00fcr steht wurde die Website mit der aktuellen Version 6.1.5 entwickelt. Ein Upgrade von der Version 6.1 auf die Version 6.2 LTS,... Projekte Weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/artif.com\/blog\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html\" \/>\n<meta property=\"og:site_name\" content=\"Blog artif T\u00fcbingen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/TYPO3-Agentur-artif-Gmbh-Co-KG\/101490748200\" \/>\n<meta property=\"article:published_time\" content=\"2013-09-24T07:53:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-31T09:35:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/artif.com\/blog\/wp-content\/uploads\/2013\/09\/Selbst\u00e4ndige-Schule-www_selbstst\u00e4ndige-schule_de.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1598\" \/>\n\t<meta property=\"og:image:height\" content=\"1224\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Andreas Brus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@artifcom\" \/>\n<meta name=\"twitter:site\" content=\"@artifcom\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andreas Brus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/artif.com\\\/blog\\\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/artif.com\\\/blog\\\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html\"},\"author\":{\"name\":\"Andreas Brus\",\"@id\":\"https:\\\/\\\/artif.com\\\/blog\\\/#\\\/schema\\\/person\\\/23ac7b0aacd4a4c89b1961e28dd37c0a\"},\"headline\":\"Neue TYPO3-Website f\u00fcr das Projekt &#8222;Selbstst\u00e4ndige Schule&#8220;\",\"datePublished\":\"2013-09-24T07:53:12+00:00\",\"dateModified\":\"2022-01-31T09:35:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/artif.com\\\/blog\\\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html\"},\"wordCount\":141,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/artif.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/artif.com\\\/blog\\\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/artif.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/Selbst\u00e4ndige-Schule-www_selbstst\u00e4ndige-schule_de.png\",\"keywords\":[\"Projekte\",\"TYPO3\"],\"articleSection\":[\"Projekte\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/artif.com\\\/blog\\\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/artif.com\\\/blog\\\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html\",\"url\":\"https:\\\/\\\/artif.com\\\/blog\\\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html\",\"name\":\"Neue TYPO3-Website f\u00fcr das Projekt \\\"Selbstst\u00e4ndige Schule\\\" - Blog artif T\u00fcbingen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/artif.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/artif.com\\\/blog\\\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/artif.com\\\/blog\\\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/artif.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/Selbst\u00e4ndige-Schule-www_selbstst\u00e4ndige-schule_de.png\",\"datePublished\":\"2013-09-24T07:53:12+00:00\",\"dateModified\":\"2022-01-31T09:35:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/artif.com\\\/blog\\\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/artif.com\\\/blog\\\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/artif.com\\\/blog\\\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html#primaryimage\",\"url\":\"https:\\\/\\\/artif.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/Selbst\u00e4ndige-Schule-www_selbstst\u00e4ndige-schule_de.png\",\"contentUrl\":\"https:\\\/\\\/artif.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/Selbst\u00e4ndige-Schule-www_selbstst\u00e4ndige-schule_de.png\",\"width\":1598,\"height\":1224},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/artif.com\\\/blog\\\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/artif.com\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neue TYPO3-Website f\u00fcr das Projekt &#8222;Selbstst\u00e4ndige Schule&#8220;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/artif.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/artif.com\\\/blog\\\/\",\"name\":\"Blog artif T\u00fcbingen\",\"description\":\"Blog von artif aus T\u00fcbingen: Internetagentur, Webdesign und TYPO3 von den Web Experts f\u00fcr Internet und Intranet aus T\u00fcbingen.\",\"publisher\":{\"@id\":\"https:\\\/\\\/artif.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/artif.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/artif.com\\\/blog\\\/#organization\",\"name\":\"artif T\u00fcbingen\",\"url\":\"https:\\\/\\\/artif.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/artif.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/artif.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/logo-artif-cs5_rgb.png\",\"contentUrl\":\"https:\\\/\\\/artif.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/logo-artif-cs5_rgb.png\",\"width\":1902,\"height\":528,\"caption\":\"artif T\u00fcbingen\"},\"image\":{\"@id\":\"https:\\\/\\\/artif.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pages\\\/TYPO3-Agentur-artif-Gmbh-Co-KG\\\/101490748200\",\"https:\\\/\\\/x.com\\\/artifcom\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/artif.com\\\/blog\\\/#\\\/schema\\\/person\\\/23ac7b0aacd4a4c89b1961e28dd37c0a\",\"name\":\"Andreas Brus\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e1d9a4c933975d228f04533e41539195768e3917e60c27e2697f409c38d90d5f?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e1d9a4c933975d228f04533e41539195768e3917e60c27e2697f409c38d90d5f?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e1d9a4c933975d228f04533e41539195768e3917e60c27e2697f409c38d90d5f?s=96&d=identicon&r=g\",\"caption\":\"Andreas Brus\"},\"sameAs\":[\"https:\\\/\\\/artif.com\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neue TYPO3-Website f\u00fcr das Projekt \"Selbstst\u00e4ndige Schule\" - Blog artif T\u00fcbingen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/artif.com\/blog\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html","og_locale":"de_DE","og_type":"article","og_title":"Neue TYPO3-Website f\u00fcr das Projekt \"Selbstst\u00e4ndige Schule\" - Blog artif T\u00fcbingen","og_description":"Die Inhalte und das Design wurde geliefert. Die Umsetzung in standardkonformes HTML und CSS und die Integration in das TYPO3-CMS erfolgte durch artif. Da die die n\u00e4chste LTS-Version 6.2 des TYPO3-CMS vor der T\u00fcr steht wurde die Website mit der aktuellen Version 6.1.5 entwickelt. Ein Upgrade von der Version 6.1 auf die Version 6.2 LTS,... Projekte Weiterlesen","og_url":"https:\/\/artif.com\/blog\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html","og_site_name":"Blog artif T\u00fcbingen","article_publisher":"https:\/\/www.facebook.com\/pages\/TYPO3-Agentur-artif-Gmbh-Co-KG\/101490748200","article_published_time":"2013-09-24T07:53:12+00:00","article_modified_time":"2022-01-31T09:35:15+00:00","og_image":[{"width":1598,"height":1224,"url":"https:\/\/artif.com\/blog\/wp-content\/uploads\/2013\/09\/Selbst\u00e4ndige-Schule-www_selbstst\u00e4ndige-schule_de.png","type":"image\/png"}],"author":"Andreas Brus","twitter_card":"summary_large_image","twitter_creator":"@artifcom","twitter_site":"@artifcom","twitter_misc":{"Verfasst von":"Andreas Brus","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/artif.com\/blog\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html#article","isPartOf":{"@id":"https:\/\/artif.com\/blog\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html"},"author":{"name":"Andreas Brus","@id":"https:\/\/artif.com\/blog\/#\/schema\/person\/23ac7b0aacd4a4c89b1961e28dd37c0a"},"headline":"Neue TYPO3-Website f\u00fcr das Projekt &#8222;Selbstst\u00e4ndige Schule&#8220;","datePublished":"2013-09-24T07:53:12+00:00","dateModified":"2022-01-31T09:35:15+00:00","mainEntityOfPage":{"@id":"https:\/\/artif.com\/blog\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html"},"wordCount":141,"commentCount":0,"publisher":{"@id":"https:\/\/artif.com\/blog\/#organization"},"image":{"@id":"https:\/\/artif.com\/blog\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html#primaryimage"},"thumbnailUrl":"https:\/\/artif.com\/blog\/wp-content\/uploads\/2013\/09\/Selbst\u00e4ndige-Schule-www_selbstst\u00e4ndige-schule_de.png","keywords":["Projekte","TYPO3"],"articleSection":["Projekte"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/artif.com\/blog\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/artif.com\/blog\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html","url":"https:\/\/artif.com\/blog\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html","name":"Neue TYPO3-Website f\u00fcr das Projekt \"Selbstst\u00e4ndige Schule\" - Blog artif T\u00fcbingen","isPartOf":{"@id":"https:\/\/artif.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/artif.com\/blog\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html#primaryimage"},"image":{"@id":"https:\/\/artif.com\/blog\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html#primaryimage"},"thumbnailUrl":"https:\/\/artif.com\/blog\/wp-content\/uploads\/2013\/09\/Selbst\u00e4ndige-Schule-www_selbstst\u00e4ndige-schule_de.png","datePublished":"2013-09-24T07:53:12+00:00","dateModified":"2022-01-31T09:35:15+00:00","breadcrumb":{"@id":"https:\/\/artif.com\/blog\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/artif.com\/blog\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/artif.com\/blog\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html#primaryimage","url":"https:\/\/artif.com\/blog\/wp-content\/uploads\/2013\/09\/Selbst\u00e4ndige-Schule-www_selbstst\u00e4ndige-schule_de.png","contentUrl":"https:\/\/artif.com\/blog\/wp-content\/uploads\/2013\/09\/Selbst\u00e4ndige-Schule-www_selbstst\u00e4ndige-schule_de.png","width":1598,"height":1224},{"@type":"BreadcrumbList","@id":"https:\/\/artif.com\/blog\/neue-typo3-website-fuer-das-projekt-selbststaendige-schule.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/artif.com\/blog"},{"@type":"ListItem","position":2,"name":"Neue TYPO3-Website f\u00fcr das Projekt &#8222;Selbstst\u00e4ndige Schule&#8220;"}]},{"@type":"WebSite","@id":"https:\/\/artif.com\/blog\/#website","url":"https:\/\/artif.com\/blog\/","name":"Blog artif T\u00fcbingen","description":"Blog von artif aus T\u00fcbingen: Internetagentur, Webdesign und TYPO3 von den Web Experts f\u00fcr Internet und Intranet aus T\u00fcbingen.","publisher":{"@id":"https:\/\/artif.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/artif.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/artif.com\/blog\/#organization","name":"artif T\u00fcbingen","url":"https:\/\/artif.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/artif.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/artif.com\/blog\/wp-content\/uploads\/2021\/03\/logo-artif-cs5_rgb.png","contentUrl":"https:\/\/artif.com\/blog\/wp-content\/uploads\/2021\/03\/logo-artif-cs5_rgb.png","width":1902,"height":528,"caption":"artif T\u00fcbingen"},"image":{"@id":"https:\/\/artif.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/TYPO3-Agentur-artif-Gmbh-Co-KG\/101490748200","https:\/\/x.com\/artifcom"]},{"@type":"Person","@id":"https:\/\/artif.com\/blog\/#\/schema\/person\/23ac7b0aacd4a4c89b1961e28dd37c0a","name":"Andreas Brus","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/e1d9a4c933975d228f04533e41539195768e3917e60c27e2697f409c38d90d5f?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e1d9a4c933975d228f04533e41539195768e3917e60c27e2697f409c38d90d5f?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e1d9a4c933975d228f04533e41539195768e3917e60c27e2697f409c38d90d5f?s=96&d=identicon&r=g","caption":"Andreas Brus"},"sameAs":["https:\/\/artif.com\/"]}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-16 16:38:46","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/artif.com\/blog\/wp-json\/wp\/v2\/posts\/198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artif.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/artif.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/artif.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/artif.com\/blog\/wp-json\/wp\/v2\/comments?post=198"}],"version-history":[{"count":7,"href":"https:\/\/artif.com\/blog\/wp-json\/wp\/v2\/posts\/198\/revisions"}],"predecessor-version":[{"id":2413,"href":"https:\/\/artif.com\/blog\/wp-json\/wp\/v2\/posts\/198\/revisions\/2413"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/artif.com\/blog\/wp-json\/wp\/v2\/media\/199"}],"wp:attachment":[{"href":"https:\/\/artif.com\/blog\/wp-json\/wp\/v2\/media?parent=198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/artif.com\/blog\/wp-json\/wp\/v2\/categories?post=198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/artif.com\/blog\/wp-json\/wp\/v2\/tags?post=198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}